{"id":326,"date":"2024-03-05T17:40:14","date_gmt":"2024-03-05T16:40:14","guid":{"rendered":"https:\/\/hockeyclubvalenciennes.com\/?p=326"},"modified":"2024-03-05T17:40:14","modified_gmt":"2024-03-05T16:40:14","slug":"stage-de-fevrier-recapitulatif","status":"publish","type":"post","link":"https:\/\/hockeyclubvalenciennes.com\/index.php\/2024\/03\/05\/stage-de-fevrier-recapitulatif\/","title":{"rendered":"Stage de F\u00e9vrier: R\u00e9capitulatif"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La semaine derni\u00e8re se d\u00e9roulait le stage de F\u00e9vrier pour nos jeunes licenci\u00e9s du HCV. Cela fut pour eux l&rsquo;occasion de perfectionner leur comp\u00e9tences en Hockey ainsi que de se d\u00e9penser et s&rsquo;amuser avec leurs copains leurs des diff\u00e9rentes activit\u00e9s propos\u00e9es par les coachs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque matin\u00e9e \u00e9tait d\u00e9di\u00e9e \u00e0 l&rsquo;entra\u00eenement de hockey. Sous la supervision de nos entra\u00eeneurs, les jeunes stagiaires ont pu progresser afin d&rsquo;augmenter leurs comp\u00e9tences en Hockey.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"331\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1065-768x1024.jpg\" alt=\"\" class=\"wp-image-331\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1065-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1065-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1065-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1065.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"329\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1066-768x1024.jpg\" alt=\"\" class=\"wp-image-329\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1066-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1066-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1066-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1066.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"330\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1067-768x1024.jpg\" alt=\"\" class=\"wp-image-330\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1067-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1067-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1067-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1067.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"328\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1068-768x1024.jpg\" alt=\"\" class=\"wp-image-328\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1068-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1068-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1068-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1068.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"327\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1071.jpg\" alt=\"\" class=\"wp-image-327\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1071.jpg 720w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1071-225x300.jpg 225w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les activit\u00e9s propos\u00e9s nous avions une sortie au Cin\u00e9ma:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"333\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1069-768x1024.jpg\" alt=\"\" class=\"wp-image-333\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1069-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1069-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1069-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1069.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"332\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1070-1024x768.jpg\" alt=\"\" class=\"wp-image-332\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1070-1024x768.jpg 1024w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1070-300x225.jpg 300w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1070-768x576.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1070-1536x1152.jpg 1536w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1070-400x300.jpg 400w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1070.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ainsi qu&rsquo;un tournois de basket:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"335\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1072-768x1024.jpg\" alt=\"\" class=\"wp-image-335\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1072-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1072-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1072-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1072.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"334\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1073-768x1024.jpg\" alt=\"\" class=\"wp-image-334\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1073-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1073-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1073-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1073.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"336\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1074-768x1024.jpg\" alt=\"\" class=\"wp-image-336\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1074-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1074-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1074-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1074.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un autre de badminton:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"337\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1063-768x1024.jpg\" alt=\"\" class=\"wp-image-337\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1063-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1063-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1063-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1063.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"338\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1064-768x1024.jpg\" alt=\"\" class=\"wp-image-338\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1064-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1064-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1064-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1064.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mais \u00e9galement une sortie au bowling:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"341\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1059-768x1024.jpg\" alt=\"\" class=\"wp-image-341\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1059-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1059-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1059-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1059.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"339\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1060-768x1024.jpg\" alt=\"\" class=\"wp-image-339\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1060-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1060-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1060-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1060.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"340\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1061-768x1024.jpg\" alt=\"\" class=\"wp-image-340\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1061-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1061-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1061-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1061.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ou des activit\u00e9s manuelles &#8230;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"342\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1062-768x1024.jpg\" alt=\"\" class=\"wp-image-342\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1062-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1062-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1062-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1062.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"343\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1075-768x1024.jpg\" alt=\"\" class=\"wp-image-343\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1075-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1075-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1075-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1075.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Et surprise du dernier jour &#8230; nos jeunes ont eu la chance de rencontrer Brieuc Delemazure &amp; Yvan Hannoir, deux joueurs de l&rsquo;\u00e9quipe de France de Hockey. C&rsquo;\u00e9tait l&rsquo;occasion pour nos jeunes de poser leurs questions, merci \u00e0 Brieuc et Yvan pour leur visite !<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"345\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1057-768x1024.jpg\" alt=\"\" class=\"wp-image-345\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1057-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1057-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1057-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1057.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"344\" src=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1058-768x1024.jpg\" alt=\"\" class=\"wp-image-344\" srcset=\"https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1058-768x1024.jpg 768w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1058-225x300.jpg 225w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1058-1152x1536.jpg 1152w, https:\/\/hockeyclubvalenciennes.com\/wp-content\/uploads\/2024\/03\/IMG_1058.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un grand merci aux coachs pour leur temps et pr\u00e9cieux conseils pour nos jeunes !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La semaine derni\u00e8re se d\u00e9roulait le stage de F\u00e9vrier pour nos jeunes licenci\u00e9s du HCV. Cela fut pour eux l&rsquo;occasion de perfectionner leur comp\u00e9tences en &hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-326","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/posts\/326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/comments?post=326"}],"version-history":[{"count":1,"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/posts\/326\/revisions"}],"predecessor-version":[{"id":346,"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/posts\/326\/revisions\/346"}],"wp:attachment":[{"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/media?parent=326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/categories?post=326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hockeyclubvalenciennes.com\/index.php\/wp-json\/wp\/v2\/tags?post=326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}